{"id":602,"date":"2020-10-24T15:30:36","date_gmt":"2020-10-24T15:30:36","guid":{"rendered":"https:\/\/apartrenate.at\/?page_id=602"},"modified":"2022-09-17T21:30:25","modified_gmt":"2022-09-17T20:30:25","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/apartrenate.at\/en\/datenschutz\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"602\" class=\"elementor elementor-602\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0573889 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0573889\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-900eb38\" data-id=\"900eb38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ca5d7e elementor-widget elementor-widget-spacer\" data-id=\"1ca5d7e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bf103b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bf103b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-695b8ed\" data-id=\"695b8ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2adb31d elementor-widget elementor-widget-text-editor\" data-id=\"2adb31d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Datenschutzerkl\u00e4rung<\/h1>\n<h2><br>Einleitung<\/h2>\n<p>Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als &#8222;Daten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, in mobilen Applikationen sowie innerhalb externer Onlinepr\u00e4senzen, wie z.B. unserer Social-Media-Profile (nachfolgend zusammenfassend bezeichnet als &#8222;Onlineangebot\u201c).<\/p>\n<p>Die verwendeten Begriffe sind nicht geschlechtsspezifisch.<\/p>\n<h2>Verantwortliche<\/h2>\n<p>Renate Platz<br>Brandau 531<br>6555 Kappl<br>\u00d6sterreich<\/p>\n<p><a href=\"mailto:info@apartrenate.at\">info@apartrenate.at<\/a><br>+43 650 3004007<span style=\"box-sizing: border-box; border: 0px none; font-size: 18.7px; font-style: normal; margin: 0px; outline: currentcolor none 0px; padding: 0px; vertical-align: baseline; color: #595959; font-family: Oxygen, sans-serif; font-variant-ligatures: normal; font-variant-caps: normal; letter-spacing: normal; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; word-spacing: 0px; -webkit-text-stroke-width: 0px; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; background-color: #ffffff; float: none; display: inline !important; font-weight: 500;\"><br><\/span><\/p>\n<h2>\u00dcbersicht der Verarbeitungen<\/h2>\n<p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.<\/p>\n<h5>Arten der verarbeiteten Daten<\/h5>\n<ul>\n<li>Kontaktdaten<\/li>\n<li>Inhaltsdaten<\/li>\n<li>Nutzungsdaten<\/li>\n<li>Meta-\/Kommunikationsdaten<\/li>\n<\/ul>\n<h5>Kategorien betroffener Personen<\/h5>\n<ul>\n<li>Kommunikationspartner<\/li>\n<li>Nutzer<\/li>\n<\/ul>\n<h5>Zwecke der Verarbeitung<\/h5>\n<ul>\n<li>Kontaktanfragen und Kommunikation<\/li>\n<li>Sicherheitsma\u00dfnahmen<\/li>\n<li>Verwaltung und Beantwortung von Anfragen<\/li>\n<li>Feedback<\/li>\n<li>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit<\/li>\n<li>Informationstechnische Infrastruktur<\/li>\n<\/ul>\n<h3>Ma\u00dfgebliche Rechtsgrundlagen<\/h3>\n<p>Im Folgenden erhalten Sie eine \u00dcbersicht der Rechtsgrundlagen der DSGVO, auf deren Basis wir personenbezogene Daten verarbeiten. Bitte nehmen Sie zur Kenntnis, dass neben den Regelungen der DSGVO nationale Datenschutzvorgaben in Ihrem bzw. unserem Wohn- oder Sitzland gelten k\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\u00dfgeblich sein, teilen wir Ihnen diese in der Datenschutzerkl\u00e4rung mit.<\/p>\n<ul>\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO)<\/strong> &#8211; Die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten erfordern, \u00fcberwiegen.<\/li>\n<\/ul>\n<p>Zus\u00e4tzlich zu den Datenschutzregelungen der Datenschutz-Grundverordnung gelten nationale Regelungen zum Datenschutz in \u00d6sterreich. Hierzu geh\u00f6rt insbesondere das Bundesgesetz zum Schutz nat\u00fcrlicher Personen bei der Verarbeitung personenbezogener Daten (Datenschutzgesetz \u2013 DSG). Das Datenschutzgesetz enth\u00e4lt insbesondere Spezialregelungen zum Recht auf Auskunft, zum Recht auf Richtigstellung oder L\u00f6schung, zur Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\u00fcr andere Zwecke und zur \u00dcbermittlung sowie zur automatisierten Entscheidungsfindung im Einzelfall.<\/p>\n<h2>Sicherheitsma\u00dfnahmen<\/h2>\n<p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten.<\/p>\n<p>Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\/p>\n<p>TLS-Verschl\u00fcsselung (https): Um Ihre via unserem Online-Angebot \u00fcbermittelten Daten zu sch\u00fctzen, nutzen wir eine TLS-Verschl\u00fcsselung. Sie erkennen derart verschl\u00fcsselte Verbindungen an dem Pr\u00e4fix https:\/\/ in der Adresszeile Ihres Browsers.<\/p>\n<h2>L\u00f6schung von Daten<\/h2>\n<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der gesetzlichen Vorgaben gel\u00f6scht, sobald deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse entfallen (z.B. wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\u00fcr den Zweck nicht erforderlich sind). Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\u00e4nkt. D.h., die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person erforderlich ist.<\/p>\n<p>Unsere Datenschutzhinweise k\u00f6nnen ferner weitere Angaben zu der Aufbewahrung und L\u00f6schung von Daten beinhalten, die f\u00fcr die jeweiligen Verarbeitungen vorrangig gelten.<\/p>\n<h2>Einsatz von Cookies<\/h2>\n<p>Cookies sind kleine Textdateien, bzw. sonstige Speichervermerke, die Informationen auf Endger\u00e4ten speichern und Informationen aus den Endger\u00e4ten auslesen. Z.B. um den Login-Status in einem Nutzerkonto, einen Warenkorbinhalt in einem E-Shop, die aufgerufenen Inhalte oder verwendete Funktionen eines Onlineangebotes speichern. Cookies k\u00f6nnen ferner zu unterschiedlichen Zwecken eingesetzt werden, z.B. zu Zwecken der Funktionsf\u00e4higkeit, Sicherheit und Komfort von Onlineangeboten sowie der Erstellung von Analysen der Besucherstr\u00f6me.<\/p>\n<p><strong>Hinweise zur Einwilligung: <\/strong>Wir setzen Cookies im Einklang mit den gesetzlichen Vorschriften ein. Daher holen wir von den Nutzern eine vorhergehende Einwilligung ein, au\u00dfer wenn diese gesetzlich nicht gefordert ist. Eine Einwilligung ist insbesondere nicht notwendig, wenn das Speichern und das Auslesen der Informationen, also auch von Cookies, unbedingt erforderlich sind, um dem den Nutzern einen von ihnen ausdr\u00fccklich gew\u00fcnschten Telemediendienst (also unser Onlineangebot) zur Verf\u00fcgung zu stellen. Die widerrufliche Einwilligung wird gegen\u00fcber den Nutzern deutlich kommuniziert und enth\u00e4lt die Informationen zu der jeweiligen Cookie-Nutzung.<\/p>\n<p><strong>Hinweise zu datenschutzrechtlichen Rechtsgrundlagen: <\/strong>Auf welcher datenschutzrechtlichen Rechtsgrundlage wir die personenbezogenen Daten der Nutzer mit Hilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir Nutzer um eine Einwilligung bitten. Falls die Nutzer einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebotes und Verbesserung seiner Nutzbarkeit) verarbeitet oder, wenn dies im Rahmen der Erf\u00fcllung unserer vertraglichen Pflichten erfolgt, wenn der Einsatz von Cookies erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\u00fcllen. Zu welchen Zwecken die Cookies von uns verarbeitet werden, dar\u00fcber kl\u00e4ren wir im Laufe dieser Datenschutzerkl\u00e4rung oder im Rahmen von unseren Einwilligungs- und Verarbeitungsprozessen auf.<\/p>\n<p><strong>Speicherdauer:&nbsp;<\/strong>Im Hinblick auf die Speicherdauer werden die folgenden Arten von Cookies unterschieden:<\/p>\n<ul>\n<li><strong>Tempor\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies):<\/strong>&nbsp;Tempor\u00e4re Cookies werden sp\u00e4testens gel\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und sein Endger\u00e4t (z.B. Browser oder mobile Applikation) geschlossen hat.<\/li>\n<li><strong>Permanente Cookies:<\/strong> Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Endger\u00e4tes gespeichert. So k\u00f6nnen beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die mit Hilfe von Cookies erhobenen Daten der Nutzer zur Reichweitenmessung verwendet werden. Sofern wir Nutzern&nbsp;keine expliziten Angaben zur Art und Speicherdauer von Cookies mitteilen (z. B. im Rahmen der Einholung der Einwilligung), sollten Nutzer davon ausgehen, dass Cookies permanent sind und die Speicherdauer bis zu zwei Jahre betragen kann.<\/li>\n<\/ul>\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out): <\/strong>Nutzer k\u00f6nnen die von ihnen abgegebenen Einwilligungen jederzeit widerrufen und zudem einen Widerspruch gegen die Verarbeitung entsprechend&nbsp;den gesetzlichen Vorgaben im Art. 21 DSGVO einlegen.&nbsp;Nutzer k\u00f6nnen ihren Widerspruch auch \u00fcber die Einstellungen ihres Browsers erkl\u00e4ren, z.B. durch Deaktivierung der Verwendung von Cookies (wobei dadurch auch die Funktionalit\u00e4t unserer Online-Dienste eingeschr\u00e4nkt sein kann). Ein Widerspruch gegen die Verwendung von Cookies zu Online-Marketing-Zwecken kann auch \u00fcber die Websites <a href=\"https:\/\/optout.aboutads.info\" target=\"_blank\" rel=\"noopener\">https:\/\/optout.aboutads.info<\/a> und <a href=\"https:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youronlinechoices.com\/<\/a> erkl\u00e4rt werden.<\/p>\n<p><strong>Weitere Hinweise zu Verarbeitungsprozessen, Verfahren und Diensten:<\/strong><\/p>\n<ul>\n<li><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung: <\/strong>Wir setzen ein Verfahren zum Cookie-Einwilligungs-Management ein, in dessen Rahmen die Einwilligungen der Nutzer in den Einsatz von Cookies, bzw. der im Rahmen des Cookie-Einwilligungs-Management-Verfahrens genannten Verarbeitungen und Anbieter eingeholt sowie von den Nutzern verwaltet und widerrufen werden k\u00f6nnen. Hierbei wird die Einwilligungserkl\u00e4rung gespeichert, um deren Abfrage nicht erneut wiederholen zu m\u00fcssen und die Einwilligung entsprechend der gesetzlichen Verpflichtung nachweisen zu k\u00f6nnen. Die Speicherung kann serverseitig und\/oder in einem Cookie (sogenanntes Opt-In-Cookie, bzw. mithilfe vergleichbarer Technologien) erfolgen, um die Einwilligung einem Nutzer, bzw. dessen Ger\u00e4t zuordnen zu k\u00f6nnen. Vorbehaltlich individueller Angaben zu den Anbietern von Cookie-Management-Diensten, gelten die folgenden Hinweise: Die Dauer der Speicherung der Einwilligung kann bis zu zwei Jahren betragen. Hierbei wird ein pseudonymer Nutzer-Identifikator gebildet und mit dem Zeitpunkt der Einwilligung, Angaben zur Reichweite der Einwilligung (z. B. welche Kategorien von Cookies und\/oder Diensteanbieter) sowie dem Browser, System und verwendeten Endger\u00e4t gespeichert.<\/li>\n<li><strong>Complianz: <\/strong>Cookie-Einwilligungs-Management; <strong>Dienstanbieter:<\/strong> Lokal auf unserem Server gehostet, keine Datenweitergabe an Dritte; <strong>Website:<\/strong> <a href=\"https:\/\/complianz.io\/\" target=\"_blank\" rel=\"noopener\">https:\/\/complianz.io\/<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/complianz.io\/legal\/\" target=\"_blank\" rel=\"noopener\">https:\/\/complianz.io\/legal\/<\/a>; <strong>Weitere Informationen:<\/strong> Es werden eine individuelle Nutzer-ID, Sprache sowie Arten der Einwilligungen und der Zeitpunkt ihrer Abgabe serverseitig und im Cookie auf dem Ger\u00e4t der Nutzer gespeichert.<\/li>\n<\/ul>\n<h2>Bereitstellung des Onlineangebotes und Webhosting<\/h2>\n<p>Wir verarbeiten die Daten der Nutzer, um ihnen unsere Online-Dienste zur Verf\u00fcgung stellen zu k\u00f6nnen. Zu diesem Zweck verarbeiten wir die IP-Adresse des Nutzers, die notwendig ist, um die Inhalte und Funktionen unserer Online-Dienste an den Browser oder das Endger\u00e4t der Nutzer zu \u00fcbermitteln.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten); Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen); Inhaltsdaten (z.B. Eingaben in Onlineformularen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit; Informationstechnische Infrastruktur (Betrieb und Bereitstellung von Informationssystemen und technischen Ger\u00e4ten (Computer, Server etc.).); Sicherheitsma\u00dfnahmen.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n<p><strong>Weitere Hinweise zu Verarbeitungsprozessen, Verfahren und Diensten:<\/strong><\/p>\n<ul>\n<li><strong>Bereitstellung Onlineangebot auf gemietetem Speicherplatz: <\/strong>F\u00fcr die Bereitstellung unseres Onlineangebotes nutzen wir Speicherplatz, Rechenkapazit\u00e4t und Software, die wir von einem entsprechenden Serveranbieter (auch &#8222;Webhoster&#8220; genannt) mieten oder anderweitig beziehen; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<li><strong>Erhebung von Zugriffsdaten und Logfiles: <\/strong>Der Zugriff auf unser Onlineangebot wird in Form von so genannten &#8222;Server-Logfiles&#8220; protokolliert. Zu den Serverlogfiles k\u00f6nnen die Adresse und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\u00f6ren. Die Serverlogfiles k\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine \u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t sicherzustellen; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO); <strong>L\u00f6schung von Daten:<\/strong> Logfile-Informationen werden f\u00fcr die Dauer von maximal 30 Tagen gespeichert und danach gel\u00f6scht oder anonymisiert. Daten, deren weitere Aufbewahrung zu Beweiszwecken erforderlich ist, sind bis zur endg\u00fcltigen Kl\u00e4rung des jeweiligen Vorfalls von der L\u00f6schung ausgenommen.<\/li>\n<li><strong>WordPress.com: <\/strong>Hosting und Software f\u00fcr die Erstellung, Bereitstellung und den Betrieb von Websites, Blogs und anderen Onlineangeboten; <strong>Dienstanbieter:<\/strong> Aut O\u2019Mattic A8C Irland Ltd., Grand Canal Dock, 25 Herbert Pl, Dublin, D02 AY86, Irland; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO); <strong>Website:<\/strong> <a href=\"https:\/\/wordpress.com\" target=\"_blank\" rel=\"noopener\">https:\/\/wordpress.com<\/a>; <strong>Datenschutzerkl\u00e4rung:<\/strong> <a href=\"https:\/\/automattic.com\/de\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/automattic.com\/de\/privacy\/<\/a>; <strong>Auftragsverarbeitungsvertrag:<\/strong> <a href=\"https:\/\/wordpress.com\/support\/data-processing-agreements\/\" target=\"_blank\" rel=\"noopener\">https:\/\/wordpress.com\/support\/data-processing-agreements\/<\/a>.<\/li>\n<\/ul>\n<h2>Kontakt- und Anfragenverwaltung<\/h2>\n<p>Bei der Kontaktaufnahme mit uns (z.B. per Kontaktformular, E-Mail, Telefon oder via soziale Medien) sowie im Rahmen bestehender Nutzer- und Gesch\u00e4ftsbeziehungen werden die Angaben der anfragenden Personen verarbeitet soweit dies zur Beantwortung der Kontaktanfragen und etwaiger angefragter Ma\u00dfnahmen erforderlich ist.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Kontaktdaten (z.B. E-Mail, Telefonnummern); Inhaltsdaten (z.B. Eingaben in Onlineformularen); Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten); Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner.<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kontaktanfragen und Kommunikation; Verwaltung und Beantwortung von Anfragen; Feedback (z.B. Sammeln von Feedback via Online-Formular); Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n<h2>Plugins und eingebettete Funktionen sowie Inhalte<\/h2>\n<p>Wir binden in unser Onlineangebot Funktions- und Inhaltselemente ein, die von den Servern ihrer jeweiligen Anbieter (nachfolgend bezeichnet als &#8222;Drittanbieter\u201d) bezogen werden. Dabei kann es sich zum Beispiel um Grafiken, Videos oder Stadtpl\u00e4ne handeln (nachfolgend einheitlich bezeichnet als &#8222;Inhalte\u201d).<\/p>\n<p>Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer verarbeiten, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-Adresse ist damit f\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\u00fchen uns, nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte verwenden. Drittanbieter k\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken, auch als &#8222;Web Beacons&#8220; bezeichnet) f\u00fcr statistische oder Marketingzwecke verwenden. Durch die &#8222;Pixel-Tags&#8220; k\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Webseite, ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen ferner in Cookies auf dem Ger\u00e4t der Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und zum Betriebssystem, zu verweisenden Webseiten, zur Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebotes enthalten als auch mit solchen Informationen aus anderen Quellen verbunden werden.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten); Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n<p><strong>Weitere Hinweise zu Verarbeitungsprozessen, Verfahren und Diensten:<\/strong><\/p>\n<ul>\n<li><strong>Google Fonts (Bereitstellung auf eigenem Server): <\/strong>Schriftarten (&#8222;Google Fonts&#8220;) zwecks einer nutzerfreundlichen Darstellung unseres Onlineangebotes; <strong>Dienstanbieter:<\/strong> Die Google Fonts werden auf unserem Server gehostet, es werden keine Daten an Google \u00fcbermittelt; <strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f) DSGVO).<\/li>\n<\/ul>\n<h2>\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/h2>\n<p>Wir bitten Sie, sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird.<\/p>\n<p>Sofern wir in dieser Datenschutzerkl\u00e4rung Adressen und Kontaktinformationen von Unternehmen und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \u00fcber die Zeit \u00e4ndern k\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\u00fcfen.<\/p>\n<h2>Rechte der betroffenen Personen<\/h2>\n<p>Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 21 DSGVO ergeben:<\/p>\n<ul>\n<li><strong>Widerspruchsrecht: Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\/strong><\/li>\n<li><strong>Widerrufsrecht bei Einwilligungen:<\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\/li>\n<li><strong>Auskunftsrecht:<\/strong> Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\/li>\n<li><strong>Recht auf Berichtigung:<\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/li>\n<li><strong>Recht auf L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe der gesetzlichen Vorgaben eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/li>\n<li><strong>Recht auf Daten\u00fcbertragbarkeit:<\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\/li>\n<li><strong>Beschwerde bei Aufsichtsbeh\u00f6rde:<\/strong> Sie haben unbeschadet eines anderweitigen verwaltungsrechtlichen oder gerichtlichen Rechtsbehelfs das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthaltsorts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes, wenn Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten gegen die Vorgaben der DSGVO verst\u00f6\u00dft.<\/li>\n<\/ul>\n<h2>Begriffsdefinitionen<\/h2>\n<p>In diesem Abschnitt erhalten Sie eine \u00dcbersicht \u00fcber die in dieser Datenschutzerkl\u00e4rung verwendeten Begrifflichkeiten. Viele der Begriffe sind dem Gesetz entnommen und vor allem im Art. 4 DSGVO definiert. Die gesetzlichen Definitionen sind verbindlich. Die nachfolgenden Erl\u00e4uterungen sollen dagegen vor allem dem Verst\u00e4ndnis dienen. Die Begriffe sind alphabetisch sortiert.<\/p>\n<ul>\n<li><strong>Personenbezogene Daten:<\/strong> &#8222;Personenbezogene Daten\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden &#8222;betroffene Person\u201c) beziehen; als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.<\/li>\n<li><strong>Verantwortlicher:<\/strong> Als &#8222;Verantwortlicher\u201c wird die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\/li>\n<li><strong>Verarbeitung:<\/strong> &#8222;Verarbeitung&#8220; ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten, sei es das Erheben, das Auswerten, das Speichern, das \u00dcbermitteln oder das L\u00f6schen.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Einleitung Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als &#8222;Daten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-602","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl<\/title>\n<meta name=\"description\" content=\"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartrenate.at\/en\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl\" \/>\n<meta property=\"og:description\" content=\"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartrenate.at\/en\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Apart Renate - Kappl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-17T20:30:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/apartrenate.at\/datenschutz\/\",\"url\":\"https:\/\/apartrenate.at\/datenschutz\/\",\"name\":\"Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl\",\"isPartOf\":{\"@id\":\"https:\/\/apartrenate.at\/#website\"},\"datePublished\":\"2020-10-24T15:30:36+00:00\",\"dateModified\":\"2022-09-17T20:30:25+00:00\",\"description\":\"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at\",\"breadcrumb\":{\"@id\":\"https:\/\/apartrenate.at\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/apartrenate.at\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/apartrenate.at\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/apartrenate.at\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/apartrenate.at\/#website\",\"url\":\"https:\/\/apartrenate.at\/\",\"name\":\"Apart Renate - Kappl\",\"description\":\"Urlaub. Wohlf\u00fchlen. Abschalten.\",\"publisher\":{\"@id\":\"https:\/\/apartrenate.at\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/apartrenate.at\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/apartrenate.at\/#organization\",\"name\":\"Apart Renate\",\"url\":\"https:\/\/apartrenate.at\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/apartrenate.at\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/apartrenate.at\/wp-content\/uploads\/2020\/10\/logo-website-apart-renate-kappl-350x100-rahmen.png\",\"contentUrl\":\"https:\/\/apartrenate.at\/wp-content\/uploads\/2020\/10\/logo-website-apart-renate-kappl-350x100-rahmen.png\",\"width\":350,\"height\":100,\"caption\":\"Apart Renate\"},\"image\":{\"@id\":\"https:\/\/apartrenate.at\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl","description":"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartrenate.at\/en\/datenschutz\/","og_locale":"en_GB","og_type":"article","og_title":"Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl","og_description":"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at","og_url":"https:\/\/apartrenate.at\/en\/datenschutz\/","og_site_name":"Apart Renate - Kappl","article_modified_time":"2022-09-17T20:30:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apartrenate.at\/datenschutz\/","url":"https:\/\/apartrenate.at\/datenschutz\/","name":"Datenschutz erkl\u00e4rung (DSGVO) - Apart Renate - Kappl","isPartOf":{"@id":"https:\/\/apartrenate.at\/#website"},"datePublished":"2020-10-24T15:30:36+00:00","dateModified":"2022-09-17T20:30:25+00:00","description":"In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten der Website apartrenate.at","breadcrumb":{"@id":"https:\/\/apartrenate.at\/datenschutz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartrenate.at\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/apartrenate.at\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/apartrenate.at\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/apartrenate.at\/#website","url":"https:\/\/apartrenate.at\/","name":"Apart Renate - Kappl","description":"Vacation. Feel Good. Switch Off.","publisher":{"@id":"https:\/\/apartrenate.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartrenate.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/apartrenate.at\/#organization","name":"Apart Renate","url":"https:\/\/apartrenate.at\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/apartrenate.at\/#\/schema\/logo\/image\/","url":"https:\/\/apartrenate.at\/wp-content\/uploads\/2020\/10\/logo-website-apart-renate-kappl-350x100-rahmen.png","contentUrl":"https:\/\/apartrenate.at\/wp-content\/uploads\/2020\/10\/logo-website-apart-renate-kappl-350x100-rahmen.png","width":350,"height":100,"caption":"Apart Renate"},"image":{"@id":"https:\/\/apartrenate.at\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/pages\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/comments?post=602"}],"version-history":[{"count":19,"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/pages\/602\/revisions"}],"predecessor-version":[{"id":1434,"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/pages\/602\/revisions\/1434"}],"wp:attachment":[{"href":"https:\/\/apartrenate.at\/en\/wp-json\/wp\/v2\/media?parent=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}